{"id":13298,"date":"2026-04-15T15:50:22","date_gmt":"2026-04-15T15:50:22","guid":{"rendered":"https:\/\/fluidnatek.com\/success-stories\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/"},"modified":"2026-04-16T06:42:46","modified_gmt":"2026-04-16T06:42:46","slug":"como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea","status":"publish","type":"success-story","link":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/","title":{"rendered":"C\u00f3mo APPLUS\/RESCOLL desarroll\u00f3 andamios (scaffolds) biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea"},"content":{"rendered":"<p>En este caso pr\u00e1ctico, analizamos c\u00f3mo <strong>MARILYS Blanchy, experta en materiales para dispositivos m\u00e9dicos en <a href=\"https:\/\/www.applus.com\/global\/en\/about-us\/our-brands\/applus+-rescoll-\">APPLUS\/RESCOLL<\/a><\/strong>, abord\u00f3 los retos que plantea el desarrollo de andamios (scaffolds) biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando nuestra tecnolog\u00eda de electrospinning.<\/p>\n<h2>Desaf\u00edo<\/h2>\n<p>\u00abEn nuestro esfuerzo por crear andamios biomim\u00e9ticos avanzados, nos enfrentamos a un reto importante: reproducir tejido totalmente funcional y vascularizado. Estos andamios sirven de plantilla, lo que permite que el tejido end\u00f3geno se reconstruya o se regenere de forma eficaz\u00bb.<\/p>\n<figure id=\"attachment_13258\" aria-describedby=\"caption-attachment-13258\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13258 size-large\" src=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-1024x703.png\" alt=\"ingenier\u00eda tisular\" width=\"1024\" height=\"703\" srcset=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-1024x703.png 1024w, https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-300x206.png 300w, https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-768x527.png 768w, https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-1536x1054.png 1536w, https:\/\/fluidnatek.com\/wp-content\/uploads\/tissue-enginering-wikipedia-2048x1406.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-13258\" class=\"wp-caption-text\">Tissue enginering. Caption: wikipedia.org<\/figcaption><\/figure>\n<h2>Soluci\u00f3n<\/h2>\n<p>Para dar respuesta a estas necesidades, APPLUS\/RESCOLL desarroll\u00f3 un enfoque multimaterial y multiescala que combina un andamio tridimensional que proporciona soporte mec\u00e1nico con una membrana electrohilada dise\u00f1ada como dep\u00f3sito de f\u00e1rmacos e interfaz interactiva con las c\u00e9lulas. Utilizaron el sistema de electrospinning <a href=\"https:\/\/fluidnatek.com\/es\/maquinas-electrospinning\/fluidnatek-le-100-electrohilado-nanofibras\/\">Fluidnatek LE-100<\/a> para ajustar con precisi\u00f3n la morfolog\u00eda de las fibras, la arquitectura del andamio y el comportamiento de liberaci\u00f3n.<\/p>\n<p>Marilys Blanchy: \u00abCon el equipo Fluidnatek LE-100 podemos controlar el entorno (temperatura y humedad relativa), disponemos de dos fuentes de alta tensi\u00f3n, diferentes geometr\u00edas de colectores (giratorios o planos) y podemos ajustar con precisi\u00f3n el caudal y el desplazamiento lineal de la boquilla durante el proceso de fabricaci\u00f3n\u00bb.<\/p>\n<p>Especificaciones empleadas:<\/p>\n<ul>\n<li>Temperatura 20 &#8211; 50\u00b0 C<\/li>\n<li>Humedad relativa 10 -90%<\/li>\n<li>2 Alto voltaje: 0 \u2013 30 kV et -30-0 kV<\/li>\n<li>Colector giratorio: 2 di\u00e1metros (18 mm y 100 mm), v = 0-2000 rpm<\/li>\n<li>Flat collector ; 40*40 cm<\/li>\n<li>Caudales m\u00e1ximo y m\u00ednimo: 1.257-0,73 ml\/h<\/li>\n<li>2 jeringas de bombeo calentadas hasta 120 \u00b0C<\/li>\n<li>X desplazamiento: 0-100 mm\/s<\/li>\n<\/ul>\n<p>Gracias a estas funciones, el equipo:<\/p>\n<ul>\n<li>Se ajustaron los par\u00e1metros del proceso y ambientales, como la humedad relativa, para modificar la calidad de la fibra, el grosor total, la porosidad y la densidad de las zonas de reparaci\u00f3n.<\/li>\n<li>Se fijaron como objetivo unos di\u00e1metros de fibra de aproximadamente 1-2 micr\u00f3metros y unos espesores de parche comprendidos entre 500 micr\u00f3metros y 1 mil\u00edmetro, y posteriormente se verificaron estos valores experimentalmente.<\/li>\n<li>Se ha caracterizado y mejorado la humectabilidad de la superficie, partiendo de una matriz altamente hidr\u00f3foba con un \u00e1ngulo de contacto de unos 130\u00b0, y actuando sobre el estado de la superficie para obtener una membrana m\u00e1s hidr\u00f3fila que favorezca la adhesi\u00f3n celular.<\/li>\n<li>Se han fabricado fibras de tipo n\u00facleo-cubierta utilizando dos soluciones polim\u00e9ricas, con lo que se han obtenido n\u00facleos de unos 60 nan\u00f3metros y cubiertas de entre 120 y 200 nan\u00f3metros, tal y como ha confirmado el microscopio electr\u00f3nico de transmisi\u00f3n.<\/li>\n<li>Se evalu\u00f3 la cin\u00e9tica de liberaci\u00f3n de una mol\u00e9cula modelo (calcine) a partir de las fibras obtenidas por electrospinning y se demostr\u00f3 que, aunque los perfiles generales de liberaci\u00f3n eran similares, la cantidad total liberada pod\u00eda ajustarse modificando los par\u00e1metros del proceso de electrospinning.<\/li>\n<\/ul>\n<figure id=\"attachment_13262\" aria-describedby=\"caption-attachment-13262\" style=\"width: 991px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13262 size-large\" src=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-991x1024.png\" alt=\"Matriz obtenida\" width=\"991\" height=\"1024\" srcset=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-991x1024.png 991w, https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-290x300.png 290w, https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-768x794.png 768w, https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-1486x1536.png 1486w, https:\/\/fluidnatek.com\/wp-content\/uploads\/mat-obtained-1982x2048.png 1982w\" sizes=\"auto, (max-width: 991px) 100vw, 991px\" \/><figcaption id=\"caption-attachment-13262\" class=\"wp-caption-text\">Matriz obtenida. Imagen: APPLUS\/RESCOLL<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13299 size-large\" src=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES-1024x320.png\" alt=\"Powered by Fluidnatek Applus-ES\" width=\"1024\" height=\"320\" srcset=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES-1024x320.png 1024w, https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES-300x94.png 300w, https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES-768x240.png 768w, https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES-1536x480.png 1536w, https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-by-Fluidnatek-Applus-ES.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Resultados<\/h2>\n<p>Mediante la combinaci\u00f3n de un proceso de electrospinning controlado con una minuciosa optimizaci\u00f3n de los materiales y los procesos, APPLUS\/RESCOLL demostr\u00f3 que pod\u00eda:<\/p>\n<ul>\n<li>Fabricar matrices electrohiladas con un di\u00e1metro, un grosor, una porosidad y una densidad de fibra definidos, adecuadas para aplicaciones de ingenier\u00eda tisular.<\/li>\n<li>Modificar la hidrofilia de la superficie para favorecer la adhesi\u00f3n y la integraci\u00f3n celular.<\/li>\n<li>Generar fibras de estructura n\u00facleo-cubierta reproducibles, capaces de encapsular principios activos en forma liposomal y que permitan ajustar la cantidad de liberaci\u00f3n a lo largo del tiempo.<\/li>\n<li>Trabajar para lograr una producci\u00f3n escalable y con consistencia entre lotes utilizando materiales de grado m\u00e9dico, al tiempo que se estudian las condiciones de esterilizaci\u00f3n para preservar las propiedades tanto de las fibras como de los principios activos incorporados.<\/li>\n<\/ul>\n<figure id=\"attachment_13260\" aria-describedby=\"caption-attachment-13260\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13260 size-medium\" src=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold-300x300.png\" alt=\"andamio biomim\u00e9tico\" width=\"300\" height=\"300\" srcset=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold-300x300.png 300w, https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold-1024x1024.png 1024w, https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold-150x150.png 150w, https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold-768x768.png 768w, https:\/\/fluidnatek.com\/wp-content\/uploads\/biomimetic-scaffold.png 1494w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-13260\" class=\"wp-caption-text\">Andamio biomim\u00e9tico. Imagen: APPLUS\/RESCOLL<\/figcaption><\/figure>\n<p>\u00abEl electrospinning ha demostrado ser un punto de inflexi\u00f3n en nuestra investigaci\u00f3n, ampliando los l\u00edmites de lo que es posible en la ingenier\u00eda tisular\u00bb. Marilys Blanchy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este caso pr\u00e1ctico, analizamos c\u00f3mo MARILYS Blanchy, experta en materiales para dispositivos m\u00e9dicos en APPLUS\/RESCOLL, abord\u00f3 los retos que plantea el desarrollo de andamios (scaffolds) biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando nuestra tecnolog\u00eda de electrospinning. Desaf\u00edo \u00abEn nuestro esfuerzo por crear andamios biomim\u00e9ticos avanzados, nos enfrentamos a un reto importante: reproducir tejido totalmente [&#8230;]\n","protected":false},"featured_media":13273,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"category-case-studies":[264],"class_list":["post-13298","success-story","type-success-story","status-publish","has-post-thumbnail","hentry","category-case-studies-biomedico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>caso de \u00e9xito applus<\/title>\n<meta name=\"description\" content=\"APPLUS\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"caso de \u00e9xito applus\" \/>\n<meta property=\"og:description\" content=\"APPLUS\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluidnatek\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T06:42:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-Fluidnatek-Applus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/\",\"name\":\"caso de \u00e9xito applus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/Powered-Fluidnatek-Applus.png\",\"datePublished\":\"2026-04-15T15:50:22+00:00\",\"dateModified\":\"2026-04-16T06:42:46+00:00\",\"description\":\"APPLUS\\\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/Powered-Fluidnatek-Applus.png\",\"contentUrl\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/Powered-Fluidnatek-Applus.png\",\"width\":1920,\"height\":600,\"caption\":\"Powered Fluidnatek Applus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/caso-exito\\\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo APPLUS\\\/RESCOLL desarroll\u00f3 andamios (scaffolds) biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/\",\"name\":\"Fluidnatek\",\"description\":\"Your premium partner in Electrospinning-Electrospraying Equipment\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"caso de \u00e9xito applus","description":"APPLUS\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/","og_locale":"es_ES","og_type":"article","og_title":"caso de \u00e9xito applus","og_description":"APPLUS\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek","og_url":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/","og_site_name":"Fluidnatek","article_modified_time":"2026-04-16T06:42:46+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-Fluidnatek-Applus.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/","url":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/","name":"caso de \u00e9xito applus","isPartOf":{"@id":"https:\/\/fluidnatek.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/#primaryimage"},"image":{"@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/#primaryimage"},"thumbnailUrl":"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-Fluidnatek-Applus.png","datePublished":"2026-04-15T15:50:22+00:00","dateModified":"2026-04-16T06:42:46+00:00","description":"APPLUS\/RESCOLL ha desarrollado andamios biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea utilizando la tecnolog\u00eda de electrospinning de Fluidnatek","breadcrumb":{"@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/#primaryimage","url":"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-Fluidnatek-Applus.png","contentUrl":"https:\/\/fluidnatek.com\/wp-content\/uploads\/Powered-Fluidnatek-Applus.png","width":1920,"height":600,"caption":"Powered Fluidnatek Applus"},{"@type":"BreadcrumbList","@id":"https:\/\/fluidnatek.com\/es\/caso-exito\/como-applus-rescoll-desarrollo-andamios-scaffolds-biomimeticos-avanzados-para-la-regeneracion-osea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluidnatek.com\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo APPLUS\/RESCOLL desarroll\u00f3 andamios (scaffolds) biomim\u00e9ticos avanzados para la regeneraci\u00f3n \u00f3sea"}]},{"@type":"WebSite","@id":"https:\/\/fluidnatek.com\/es\/#website","url":"https:\/\/fluidnatek.com\/es\/","name":"Fluidnatek","description":"Your premium partner in Electrospinning-Electrospraying Equipment","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluidnatek.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/success-story\/13298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/success-story"}],"about":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/types\/success-story"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/media\/13273"}],"wp:attachment":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/media?parent=13298"}],"wp:term":[{"taxonomy":"category-case-studies","embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/category-case-studies?post=13298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}