{"id":5296,"date":"2024-02-05T18:24:06","date_gmt":"2024-02-05T18:24:06","guid":{"rendered":"http:\/\/fluidnatek.com\/electrospun-fiber-sponges-for-controlled-drug-delivery\/"},"modified":"2025-04-24T10:33:55","modified_gmt":"2025-04-24T10:33:55","slug":"electrospun-fiber-sponges-for-controlled-drug-delivery","status":"publish","type":"post","link":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/","title":{"rendered":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos"},"content":{"rendered":"<p>El objetivo de este trabajo es caracterizar, empleando t\u00e9cnicas no invasivas, esponjas tridimensionales fabricadas con fibras de PLA electroestiradas para su uso en aplicaciones de liberaci\u00f3n controlada de f\u00e1rmacos. Este tipo de esponjas es novedoso, por lo que todav\u00eda se desconocen los procesos fundamentales que ocurren en su interior referentes a la absorci\u00f3n de l\u00edquidos y su posterior liberaci\u00f3n.<\/p>\n<h2><strong>Introducci\u00f3n<\/strong><\/h2>\n<p>El desarrollo de sistemas de liberaci\u00f3n controlada de f\u00e1rmacos novedosos y alternativos es un \u00e1rea de investigaci\u00f3n muy activo en el campo de la industria farmac\u00e9utica. Actualmente, la liberaci\u00f3n controlada de f\u00e1rmacos se hace a trav\u00e9s de implantes preformados, micropart\u00edculas e implantes conformados in-situ. Los problemas de estos sistemas son, entre otros, una manufactura compleja, perfiles de liberaci\u00f3n indeseables, la degradaci\u00f3n autocatal\u00edtica de los pol\u00edmeros que provoca microambientes muy \u00e1cidos (pH alrededor de 2) y, en algunos casos, la necesidad de inyectar en el cuerpo disolventes org\u00e1nicos para la conformaci\u00f3n del implante.<\/p>\n<p>Una alternativa prometedora es el uso de esponjas de fibras polim\u00e9ricas (PFS, <em>Polymer Fiber Sponges<\/em>), que son andamios tridimensionales altamente porosos, hechos a partir de fibras polim\u00e9ricas obtenidas mediante electrospinning. El electrospinning es una herramienta muy vers\u00e1til para la creaci\u00f3n de andamios que permite, a partir de disoluciones polim\u00e9ricas, obtener una gran variedad de fibras electroestiradas en las que es posible ajustar su tama\u00f1o y distribuci\u00f3n, adem\u00e1s de la porosidad de la estructura. Sin embargo, generalmente su producci\u00f3n se lleva a cabo en forma de l\u00e1minas bidimensionales (2D) de poco grosor. Esto genera una estructura con un bajo volumen de poro espec\u00edfico, de manera que se precisa de incisiones m\u00e1s grandes para colocar los implantes en el lugar del tratamiento, con la consiguiente problem\u00e1tica asociada. Como soluci\u00f3n alternativa, se propone fabricar PFSs mediante secado en fr\u00edo (<em>freeze-drying<\/em>) usando fibras obtenidas mediante electrospinning. Este proceso permite obtener una matriz tridimensional (3D) compacta, estable, con una porosidad ajustable e interconectada en todas las direcciones, todo ello cualidades que favorecen la carga y posterior liberaci\u00f3n de f\u00e1rmacos. Adem\u00e1s, esta t\u00e9cnica de fabricaci\u00f3n permite ajustar tanto el tama\u00f1o de fibra como el tama\u00f1o de la propia esponja y se pueden crear a partir de distintos materiales, incluyendo pol\u00edmeros degradables.<\/p>\n<p>Respecto a la carga de f\u00e1rmacos en la esponja, se puede realizar o bien incorporando el f\u00e1rmaco en la disoluci\u00f3n que se emplea durante el electrospinning, de manera que forma parte de las propias fibras, o bien incorpor\u00e1ndolo a los poros de la PFS una vez creada. La elecci\u00f3n de un m\u00e9todo u otro depender\u00e1 de la naturaleza del propio f\u00e1rmaco y del perfil de liberaci\u00f3n que se quiera conseguir.<\/p>\n<p>En las PFSs, los par\u00e1metros que determinan su capacidad de retenci\u00f3n y de liberaci\u00f3n de f\u00e1rmacos son su permeabilidad y su hidrofobicidad. Sin embargo, los mecanismos fundamentales que ocurren en el interior de las PFSs durante estos procesos de carga y liberaci\u00f3n de f\u00e1rmacos son todav\u00eda poco conocidos. Por ello, el objetivo de esta publicaci\u00f3n cient\u00edfica es investigar estos procesos con mayor detalle mediante t\u00e9cnicas no invasivas.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Materiales y m\u00e9todos<\/strong><\/h2>\n<p>La PFS que se ha caracterizado fue fabricada a partir de fibras de PLA (<em>polylactide acid<\/em>) obtenidas mediante electrospinning. Para lograr la forma cil\u00edndrica, las fibras se conformaron mediante secado en fr\u00edo, dando lugar a una PFS con una densidad de 12.5 mg\/cm<sup>3<\/sup>, una altura de 6.1 mm y un di\u00e1metro de 8.0 mm. Para ajustar el perfil de liberaci\u00f3n de f\u00e1rmacos, se ha recubierto la PFS con PPX (poly(para xylylene)) mediante deposici\u00f3n qu\u00edmica de vapor (CVD, <em>chemical vapor deposition<\/em>), incrementando su densidad final hasta los 28 mg\/cm<sup>3<\/sup>.<\/p>\n<p>Las t\u00e9cnicas no invasivas que se han utilizado para caracterizar la absorci\u00f3n de l\u00edquidos y su posterior liberaci\u00f3n en la PFS han sido:<\/p>\n<ul>\n<li>\u00b5CT (<em>micro Computed Tomography<\/em>) para registrar im\u00e1genes 3D de la distribuci\u00f3n de l\u00edquido y aire dentro de la PFS durante la carga y liberaci\u00f3n del f\u00e1rmaco.<\/li>\n<li>NMR (<em>Nuclear Magnetic Resonance<\/em>) para estudiar los coeficientes de difusi\u00f3n.<\/li>\n<li>Espectroscop\u00eda e imagen EPR (<em>Electron Paramagnetic Resonance<\/em>) para registrar la cantidad de l\u00edquido que la PFS era capaz de absorber a lo largo del tiempo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>Resultados<\/strong><\/h2>\n<p>Desde el punto de vista mec\u00e1nico, las PFSs son capaces de mantener su forma y elasticidad en todas las pruebas llevadas a cabo, tanto en seco como en condiciones de carga de l\u00edquidos. Adem\u00e1s, los resultados demuestran que las PFSs retienen los l\u00edquidos dentro de su estructura y preservan el f\u00e1rmaco en una determinada geometr\u00eda.<\/p>\n<p>Los resultados tambi\u00e9n muestran que se pueden se pueden ajustar las propiedades de las PFSs a trav\u00e9s de la adici\u00f3n de excipientes y recubrimientos durante su fabricaci\u00f3n, de manera que se logren las caracter\u00edsticas de liberaci\u00f3n de f\u00e1rmacos deseada.<\/p>\n<p>Por todo ello, las PFSs fabricadas mediante fibras obtenidas a trav\u00e9s de electrospinning se muestran como un soporte muy vers\u00e1til para el suministro controlado de f\u00e1rmacos en diversas aplicaciones, como las farmac\u00e9uticas o las de ingenier\u00eda de tejidos.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Referencias<\/strong>:<\/h3>\n<p>Noninvasive characterization (EPR, \u03bcCT, NMR) of 3D PLA electrospun fiber sponges for controlled drug delivery<\/p>\n<p>International Journal of Pharmaceutics: X 2 (2020) 100055<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo de este trabajo es caracterizar, empleando t\u00e9cnicas no invasivas, esponjas tridimensionales fabricadas con fibras de PLA electroestiradas para su uso en aplicaciones de liberaci\u00f3n controlada de f\u00e1rmacos. Este tipo de esponjas es novedoso, por lo que todav\u00eda se desconocen los procesos fundamentales que ocurren en su interior referentes a la absorci\u00f3n de l\u00edquidos [&#8230;]\n","protected":false},"author":2,"featured_media":5208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-5296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pharma-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek\" \/>\n<meta property=\"og:description\" content=\"El objetivo de este trabajo es caracterizar, empleando t\u00e9cnicas no invasivas, esponjas tridimensionales fabricadas con fibras de PLA electroestiradas para su uso en aplicaciones de liberaci\u00f3n controlada de f\u00e1rmacos. Este tipo de esponjas es novedoso, por lo que todav\u00eda se desconocen los procesos fundamentales que ocurren en su interior referentes a la absorci\u00f3n de l\u00edquidos [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluidnatek\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T18:24:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T10:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"unanime@unanimecreativos.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"unanime@unanimecreativos.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/\"},\"author\":{\"name\":\"unanime@unanimecreativos.com\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#\\\/schema\\\/person\\\/b825716900830da5a01a8ceed51595c7\"},\"headline\":\"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos\",\"datePublished\":\"2024-02-05T18:24:06+00:00\",\"dateModified\":\"2025-04-24T10:33:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/\"},\"wordCount\":937,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/fluidnatek-bioinica-pharma.jpg\",\"articleSection\":[\"Pharma\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/\",\"name\":\"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/fluidnatek-bioinica-pharma.jpg\",\"datePublished\":\"2024-02-05T18:24:06+00:00\",\"dateModified\":\"2025-04-24T10:33:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#\\\/schema\\\/person\\\/b825716900830da5a01a8ceed51595c7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/fluidnatek-bioinica-pharma.jpg\",\"contentUrl\":\"https:\\\/\\\/fluidnatek.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/fluidnatek-bioinica-pharma.jpg\",\"width\":734,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/electrospun-fiber-sponges-for-controlled-drug-delivery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/\",\"name\":\"Fluidnatek\",\"description\":\"Your premium partner in Electrospinning-Electrospraying Equipment\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/#\\\/schema\\\/person\\\/b825716900830da5a01a8ceed51595c7\",\"name\":\"unanime@unanimecreativos.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"unanime@unanimecreativos.com\"},\"url\":\"https:\\\/\\\/fluidnatek.com\\\/es\\\/author\\\/unanimeunanimecreativos-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/","og_locale":"es_ES","og_type":"article","og_title":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek","og_description":"El objetivo de este trabajo es caracterizar, empleando t\u00e9cnicas no invasivas, esponjas tridimensionales fabricadas con fibras de PLA electroestiradas para su uso en aplicaciones de liberaci\u00f3n controlada de f\u00e1rmacos. Este tipo de esponjas es novedoso, por lo que todav\u00eda se desconocen los procesos fundamentales que ocurren en su interior referentes a la absorci\u00f3n de l\u00edquidos [...]","og_url":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/","og_site_name":"Fluidnatek","article_published_time":"2024-02-05T18:24:06+00:00","article_modified_time":"2025-04-24T10:33:55+00:00","og_image":[{"width":734,"height":480,"url":"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg","type":"image\/jpeg"}],"author":"unanime@unanimecreativos.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"unanime@unanimecreativos.com","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#article","isPartOf":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/"},"author":{"name":"unanime@unanimecreativos.com","@id":"https:\/\/fluidnatek.com\/es\/#\/schema\/person\/b825716900830da5a01a8ceed51595c7"},"headline":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos","datePublished":"2024-02-05T18:24:06+00:00","dateModified":"2025-04-24T10:33:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/"},"wordCount":937,"commentCount":0,"image":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#primaryimage"},"thumbnailUrl":"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg","articleSection":["Pharma"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/","url":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/","name":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos - Fluidnatek","isPartOf":{"@id":"https:\/\/fluidnatek.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#primaryimage"},"image":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#primaryimage"},"thumbnailUrl":"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg","datePublished":"2024-02-05T18:24:06+00:00","dateModified":"2025-04-24T10:33:55+00:00","author":{"@id":"https:\/\/fluidnatek.com\/es\/#\/schema\/person\/b825716900830da5a01a8ceed51595c7"},"breadcrumb":{"@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#primaryimage","url":"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg","contentUrl":"https:\/\/fluidnatek.com\/wp-content\/uploads\/2024\/02\/fluidnatek-bioinica-pharma.jpg","width":734,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/fluidnatek.com\/es\/electrospun-fiber-sponges-for-controlled-drug-delivery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluidnatek.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esponjas de fibras Electrospun para la administraci\u00f3n controlada de f\u00e1rmacos"}]},{"@type":"WebSite","@id":"https:\/\/fluidnatek.com\/es\/#website","url":"https:\/\/fluidnatek.com\/es\/","name":"Fluidnatek","description":"Your premium partner in Electrospinning-Electrospraying Equipment","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluidnatek.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fluidnatek.com\/es\/#\/schema\/person\/b825716900830da5a01a8ceed51595c7","name":"unanime@unanimecreativos.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"unanime@unanimecreativos.com"},"url":"https:\/\/fluidnatek.com\/es\/author\/unanimeunanimecreativos-com\/"}]}},"_links":{"self":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/posts\/5296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/comments?post=5296"}],"version-history":[{"count":3,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/posts\/5296\/revisions"}],"predecessor-version":[{"id":9362,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/posts\/5296\/revisions\/9362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/media\/5208"}],"wp:attachment":[{"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/media?parent=5296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/categories?post=5296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluidnatek.com\/es\/wp-json\/wp\/v2\/tags?post=5296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}